{"id":1282,"date":"2007-07-25T20:17:22","date_gmt":"2007-07-25T18:17:22","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2007\/07\/25\/stalker-clear-sky-les-videos-promotionnelles\/"},"modified":"2007-07-25T20:17:25","modified_gmt":"2007-07-25T18:17:25","slug":"stalker-clear-sky-les-videos-promotionnelles","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2007\/07\/25\/stalker-clear-sky-les-videos-promotionnelles\/","title":{"rendered":"S.T.A.L.K.E.R. &#8211; Clear Sky, les vid\u00e9os promotionnelles"},"content":{"rendered":"<p>GameTrailers a rapport\u00e9 du salon E3 toute une s\u00e9rie de <a href=\"http:\/\/www.gametrailers.com\/game\/5178.html\">vid\u00e9os \u00e0 propos de <strong>S.T.A.L.K.E.R. &#8211; Clear Sky<\/strong><\/a>, le jeu vid\u00e9o qui reprend les \u00e9l\u00e9ments de <em>S.T.A.L.K.E.R. &#8211; Shadow of Chernobyl<\/em>.<\/p>\n<p>En voici un exemple, mais je vous invite \u00e0 suivre le <a href=\"http:\/\/www.gametrailers.com\/game\/5178.html\">lien<\/a> pour en trouver d&rsquo;autres (y compris des vid\u00e9os \u00e0 haute r\u00e9solution).<\/p>\n<p><center><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\"  codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=8,0,0,0\" id=\"gtembed\" width=\"480\" height=\"409\"><param name=\"allowScriptAccess\" value=\"sameDomain\" \/><param name=\"movie\" value=\"http:\/\/www.gametrailers.com\/remote_wrap.php?mid=22444\"\/><param name=\"quality\" value=\"high\" \/><embed src=\"http:\/\/www.gametrailers.com\/remote_wrap.php?mid=22444\" swLiveConnect=\"true\" name=\"gtembed\" align=\"middle\" allowScriptAccess=\"sameDomain\" quality=\"high\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" type=\"application\/x-shockwave-flash\" width=\"480\" height=\"409\"><\/embed><\/object><\/center><\/p>\n<p>Le seul reproche que je ferais \u00e0 ces vid\u00e9os est que le joueur est particuli\u00e8rement peu habile et joue visiblement en <em>God mode<\/em> (il ne craint pas les balles des adversaires qui ne lui font rien). Cela permet de mieux pr\u00e9senter le jeu, mais le r\u00e9alisme s&rsquo;\u00e9croule quand on voit ces s\u00e9quences de jeu (dans <em>S.T.A.L.K.E.R. &#8211; Shadow of Chernobyl<\/em> les adversaires ne sont pas tous brillants, mais on ne peut absolument pas se promener sous leur feu et esp\u00e9rer survivre plus d&rsquo;une ou deux secondes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GameTrailers a rapport\u00e9 du salon E3 toute une s\u00e9rie de vid\u00e9os \u00e0 propos de S.T.A.L.K.E.R. &#8211; Clear Sky, le jeu vid\u00e9o qui reprend les \u00e9l\u00e9ments de S.T.A.L.K.E.R. &#8211; Shadow of Chernobyl. En voici un exemple, mais je vous invite \u00e0 suivre le lien pour en trouver d&rsquo;autres (y compris des vid\u00e9os \u00e0 haute r\u00e9solution). Le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,28],"tags":[],"class_list":["post-1282","post","type-post","status-publish","format-standard","hentry","category-film","category-jeux-video"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/1282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=1282"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/1282\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=1282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=1282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=1282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}