{"id":2090,"date":"2008-05-02T14:29:02","date_gmt":"2008-05-02T12:29:02","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2008\/05\/02\/turok-pour-tuer-quelques-dinosaures\/"},"modified":"2008-04-20T18:19:10","modified_gmt":"2008-04-20T16:19:10","slug":"turok-pour-tuer-quelques-dinosaures","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2008\/05\/02\/turok-pour-tuer-quelques-dinosaures\/","title":{"rendered":"Turok : pour tuer quelques dinosaures"},"content":{"rendered":"<p>Apr\u00e8s plus de 10 ans, Turok revient sur votre PC pour vous permettre de tuer quelques gros dinosaures sur votre \u00e9cran plat. La mission solo de ce FPS peut sembler un peu courte, mais c&rsquo;est assez fun pour avoir envie de tuer encore quelques gros l\u00e9zards de retour de la pr\u00e9histoire sur votre PC.<\/p>\n<p><center><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\"  codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=8,0,0,0\" id=\"gtembed\" width=\"480\" height=\"392\"><param name=\"allowScriptAccess\" value=\"sameDomain\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"movie\" value=\"http:\/\/www.gametrailers.com\/remote_wrap.php?mid=30162\"\/><param name=\"quality\" value=\"high\" \/><embed src=\"http:\/\/www.gametrailers.com\/remote_wrap.php?mid=30162\" swLiveConnect=\"true\" name=\"gtembed\" align=\"middle\" allowScriptAccess=\"sameDomain\" allowFullScreen=\"true\" quality=\"high\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\" type=\"application\/x-shockwave-flash\" width=\"480\" height=\"392\"><\/embed><\/object><br \/><a href=\"http:\/\/www.gametrailers.com\/player\/30161.html\">HD review<\/a><br \/><a href=\"http:\/\/www.gametrailers.com\/player\/30162.html\">SD review<\/a><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s plus de 10 ans, Turok revient sur votre PC pour vous permettre de tuer quelques gros dinosaures sur votre \u00e9cran plat. La mission solo de ce FPS peut sembler un peu courte, mais c&rsquo;est assez fun pour avoir envie de tuer encore quelques gros l\u00e9zards de retour de la pr\u00e9histoire sur votre PC. HD [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,54,28],"tags":[226,374],"class_list":["post-2090","post","type-post","status-publish","format-standard","hentry","category-film","category-graphique-affichage","category-jeux-video","tag-jeu-video","tag-pc"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2090"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2090\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}