{"id":2374,"date":"2008-09-24T11:49:24","date_gmt":"2008-09-24T09:49:24","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/?p=2374"},"modified":"2008-09-16T20:58:43","modified_gmt":"2008-09-16T18:58:43","slug":"la-vieille-et-la-bagnole","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2008\/09\/24\/la-vieille-et-la-bagnole\/","title":{"rendered":"La vieille et la bagnole"},"content":{"rendered":"<p>Il est parfois difficile de pr\u00e9voir le r\u00e9sultat d&rsquo;un combat. Maintenant, si vous prenez une vieille dame tr\u00e8s digne et une voiture (trop) rapide. Devinez qui s&rsquo;en sortira sans le moindre dommage ?<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"425\" height=\"344\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/WGBcY2IoFSg&amp;hl=en&amp;fs=1\" \/><embed type=\"application\/x-shockwave-flash\" width=\"425\" height=\"344\" src=\"http:\/\/www.youtube.com\/v\/WGBcY2IoFSg&amp;hl=en&amp;fs=1\" allowfullscreen=\"true\"><\/embed><\/object><br \/>\n<a href=\"http:\/\/www.youtube.com\/watch?v=WGBcY2IoFSg\">Link to YouTube<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est parfois difficile de pr\u00e9voir le r\u00e9sultat d&rsquo;un combat. Maintenant, si vous prenez une vieille dame tr\u00e8s digne et une voiture (trop) rapide. Devinez qui s&rsquo;en sortira sans le moindre dommage ? Link to YouTube<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,26,1,77],"tags":[],"class_list":["post-2374","post","type-post","status-publish","format-standard","hentry","category-cinema","category-film","category-inclassable","category-securite"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2374"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2374\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}