{"id":2991,"date":"2008-12-22T17:00:00","date_gmt":"2008-12-22T15:00:00","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/?p=2991"},"modified":"2010-12-21T16:11:53","modified_gmt":"2010-12-21T14:11:53","slug":"camions-autos-sans-limite-video","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2008\/12\/22\/camions-autos-sans-limite-video\/","title":{"rendered":"Camions, autos, sans limite (vid\u00e9o)"},"content":{"rendered":"<p>Vous vous souvenez certainement de l&rsquo;impressionnante solution trouv\u00e9e en Tha\u00eflade pour d\u00e9charger une excavatrice d&rsquo;un camion sans l&rsquo;aide d&rsquo;une grue ni m\u00eame d&rsquo;une rampe :<\/p>\n<p><center><object width=\"425\" height=\"344\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/FE02TxLlRQU&#038;hl=en&#038;fs=1\"><\/param><param name=\"allowFullScreen\" value=\"true\"><\/param><param name=\"allowscriptaccess\" value=\"always\"><\/param><embed src=\"http:\/\/www.youtube.com\/v\/FE02TxLlRQU&#038;hl=en&#038;fs=1\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"425\" height=\"344\"><\/embed><\/object><br \/><a href=\"http:\/\/www.youtube.com\/watch?v=FE02TxLlRQU\">YouTube link<\/a><\/center><\/p>\n<p>Mais voici plus, beaucoup plus, de <strong>fun avec des autos, des camions, des excavatrices et quelques autres grosses m\u00e9caniques<\/strong>.<\/p>\n<p>Commen\u00e7ons avec un Caterpillar de 15 tonnes qui fol\u00e2tre gentiment au soleil.<\/p>\n<p><center><object width=\"464\" height=\"376\"><param name=\"movie\" value=\"http:\/\/embed.break.com\/NjE4Nzg0\"><\/param><param name=\"allowScriptAccess\" value=\"always\"><\/param><embed src=\"http:\/\/embed.break.com\/NjE4Nzg0\" type=\"application\/x-shockwave-flash\" allowScriptAccess=always width=\"464\" height=\"376\"><\/embed><\/object><br \/><font size=1><a href=\"http:\/\/www.break.com\/index\/skills-with-a-15-ton-front-loader.html\">Skills With A 15 Ton Front Loader<\/a><\/font><\/center><\/p>\n<p>Mais pourquoi faudrait-il qu&rsquo;un Caterpillar reste au sol ? Ce serait trop triste ! C&rsquo;est bien ce que d\u00e9montre <a href=\"http:\/\/www.darkroastedblend.com\/2008\/11\/rocket-explosion-overture.html\">Dark Roasted Blend<\/a> :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.roumazeilles.net\/news\/en\/wordpress\/wp-content\/uploads\/2008\/12\/hydraulic-climbing-tower.jpg\" alt=\"hydraulic-climbing-tower\" title=\"hydraulic-climbing-tower\" width=\"495\" height=\"681\" class=\"aligncenter size-full wp-image-2737\" \/><\/p>\n<p>Quoi qu&rsquo;il en soit, ce qui \u00e9tait facile avec un engin de chantier devient parfois difficile avec une simple voiture ; ce qu&rsquo;il ne faut pas faire :<\/p>\n<p><center><object width=\"464\" height=\"376\"><param name=\"movie\" value=\"http:\/\/embed.break.com\/NTkzNDAw\"><\/param><param name=\"allowScriptAccess\" value=\"always\"><\/param><embed src=\"http:\/\/embed.break.com\/NTkzNDAw\" type=\"application\/x-shockwave-flash\" allowScriptAccess=always width=\"464\" height=\"376\"><\/embed><\/object><br \/><font size=1><a href=\"http:\/\/www.break.com\/index\/how-not-to-unload-a-car.html\">How Not To Unload A Car<\/a><\/font><\/center><\/p>\n<p>Apr\u00e8s cela, vous comprenez qu&rsquo;il faut apprendre \u00e0 r\u00e9parer votre voiture \u00e0 tout moment. Certaines personnes prennent ce conseil tr\u00e8s au s\u00e9rieux. Vraiment.<\/p>\n<p>Voici l&rsquo;histoire de cet \u00e9quipage de rally qui a vu sa voiture stopp\u00e9e dans son \u00e9lan par la rupture d&rsquo;un c\u00e2ble de commande des gaz. Impossible d&rsquo;acc\u00e9l\u00e9rer&#8230; Que feriez-vous alors ? Abandonner la course ? Vous n&rsquo;y pensez pas ! Pas pour ces gars-l\u00e0 ! L&rsquo;un d&rsquo;eux s&rsquo;installe sous le capot (!) et va manipuler lui-m\u00eame le moteur depuis cette position un peu inconfortable, jusqu&rsquo;\u00e0 finir l&rsquo;\u00e9tape.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.roumazeilles.net\/news\/en\/wordpress\/wp-content\/uploads\/2008\/12\/repair_car_in_race-300x199.jpg\" alt=\"repair_car_in_race\" title=\"repair_car_in_race\" width=\"300\" height=\"199\" class=\"aligncenter size-medium wp-image-2739\" \/><\/p>\n<p><center><embed src=\"http:\/\/videos.streetfire.net\/vidiac.swf?video=35a21900-4667-4125-8aeb-9b550131b35e\" width=\"428\" height=\"352\" allowFullScreen=\"true\" type=\"application\/x-shockwave-flash\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\"><\/embed><\/center><\/p>\n<p>C&rsquo;est la crise, vous n&rsquo;\u00eates pas pr\u00eat \u00e0 ces extr\u00e9mit\u00e9s pour garder votre voiture en fonctionnement. Vous voulez limiter votre consommation et votre impact sur la plan\u00e8te. Je vous conseille d&rsquo;acheter un camion vraiment \u00ab\u00a0z\u00e9ro-carbone\u00a0\u00bb (d&rsquo;une marque connue de batteries et piles) :<\/p>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.roumazeilles.net\/news\/en\/wordpress\/wp-content\/uploads\/2008\/12\/electric-truck.jpg\" alt=\"Image by &lt;a href=&quot;http:\/\/www.flickr.com\/photos\/sirwiseowl\/2514783918\/&quot; title=&quot;Electrick Truck&quot;&gt;SirWiseOwl. Licensed under Creative Commons license 2.0.\" title=\"electric-truck\" width=\"450\" height=\"332\" class=\"size-full wp-image-2738\" \/>\n","protected":false},"excerpt":{"rendered":"<p>Vous vous souvenez certainement de l&rsquo;impressionnante solution trouv\u00e9e en Tha\u00eflade pour d\u00e9charger une excavatrice d&rsquo;un camion sans l&rsquo;aide d&rsquo;une grue ni m\u00eame d&rsquo;une rampe : YouTube link Mais voici plus, beaucoup plus, de fun avec des autos, des camions, des excavatrices et quelques autres grosses m\u00e9caniques. Commen\u00e7ons avec un Caterpillar de 15 tonnes qui fol\u00e2tre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1429,26,1,77,4],"tags":[],"class_list":["post-2991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fabrication","category-film","category-inclassable","category-securite","category-web"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=2991"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/2991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media\/7188"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=2991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=2991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=2991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}