{"id":354,"date":"2006-05-20T23:44:13","date_gmt":"2006-05-20T22:44:13","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2006\/05\/20\/fiches-conseil-ilford\/"},"modified":"2006-05-20T23:44:13","modified_gmt":"2006-05-20T22:44:13","slug":"fiches-conseil-ilford","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2006\/05\/20\/fiches-conseil-ilford\/","title":{"rendered":"Fiches conseil Ilford"},"content":{"rendered":"<p>Ilford reste une marque de r\u00e9f\u00e9rence pour le photographe amateur malgr\u00e9 la drastique r\u00e9duction de ses activit\u00e9s maintenant plut\u00f4t centr\u00e9es sur le papier pour imprimante  jet d&rsquo;encre \u00e0 qualit\u00e9 photo. C&rsquo;est pourquoi il est plaisant de retrouver sur leur site <a href=\"http:\/\/www.ilford.fr\/docs\/conseils\/conseil.asp\">les fiches conseils d&rsquo;Ilford<\/a>. Cela comporte encore les anciens conseils pour le traitement des films et des papiers noir et blanc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ilford reste une marque de r\u00e9f\u00e9rence pour le photographe amateur malgr\u00e9 la drastique r\u00e9duction de ses activit\u00e9s maintenant plut\u00f4t centr\u00e9es sur le papier pour imprimante jet d&rsquo;encre \u00e0 qualit\u00e9 photo. C&rsquo;est pourquoi il est plaisant de retrouver sur leur site les fiches conseils d&rsquo;Ilford. Cela comporte encore les anciens conseils pour le traitement des films [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,31,7],"tags":[],"class_list":["post-354","post","type-post","status-publish","format-standard","hentry","category-imprimante-jet-dencre","category-photo","category-utiliser-son-reflex-numerique"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=354"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/354\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}