{"id":4441,"date":"2010-05-13T16:36:25","date_gmt":"2010-05-13T14:36:25","guid":{"rendered":"http:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/?p=4441"},"modified":"2010-05-14T03:00:23","modified_gmt":"2010-05-14T01:00:23","slug":"temperature-basse-temperature-haute","status":"publish","type":"post","link":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/2010\/05\/13\/temperature-basse-temperature-haute\/","title":{"rendered":"Temp\u00e9rature basse, temp\u00e9rature haute"},"content":{"rendered":"<p>Il ne s&rsquo;agit pas simplement d&rsquo;\u00e9t\u00e9 ou d&rsquo;hiver (m\u00eame si le mois de mai semble particuli\u00e8rement froid \u00e0 Paris cette ann\u00e9e), il ne s&rsquo;agit pas non plus du r\u00e9chauffement climatique (on va parler d&rsquo;une bien plus grande variation). Le <em>Rasmussen College<\/em> nous pr\u00e9sente <a href=\"http:\/\/www.rasmussen.edu\/articles\/heat-a-visual-tour.asp\">un joli poster<\/a> qui balaye la plage de temp\u00e9ratures la plus large possible pour nous faire d\u00e9couvrir la diversit\u00e9 thermique de l&rsquo;univers.<\/p>\n<p><a href=\"http:\/\/www.rasmussen.edu\/articles\/heat-a-visual-tour.asp\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-content\/uploads\/2010\/03\/Heat_A_Visual_Tour.jpg\" alt=\"Heat_A_Visual_Tour\" title=\"Heat_A_Visual_Tour\" width=\"600\" height=\"4203\" class=\"aligncenter size-full wp-image-4442\" \/><\/a><\/p>\n<p>J&rsquo;esp\u00e8re qu&rsquo;il mettront le poster en vente quelque part.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ne s&rsquo;agit pas simplement d&rsquo;\u00e9t\u00e9 ou d&rsquo;hiver (m\u00eame si le mois de mai semble particuli\u00e8rement froid \u00e0 Paris cette ann\u00e9e), il ne s&rsquo;agit pas non plus du r\u00e9chauffement climatique (on va parler d&rsquo;une bien plus grande variation). Le Rasmussen College nous pr\u00e9sente un joli poster qui balaye la plage de temp\u00e9ratures la plus large [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,59,32],"tags":[1325,1212,1324],"class_list":["post-4441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-listes","category-rechauffement-climatique","category-sciences","tag-poster","tag-science","tag-temperature"],"_links":{"self":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/4441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/comments?post=4441"}],"version-history":[{"count":0,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/posts\/4441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media\/4442"}],"wp:attachment":[{"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/media?parent=4441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/categories?post=4441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.roumazeilles.net\/news\/fr\/wordpress\/wp-json\/wp\/v2\/tags?post=4441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}